{"id":20990,"date":"2020-10-16T14:04:19","date_gmt":"2020-10-16T13:04:19","guid":{"rendered":"https:\/\/testing.hub.brussels\/export\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/"},"modified":"2020-10-16T14:04:19","modified_gmt":"2020-10-16T13:04:19","slug":"naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels","status":"publish","type":"post","link":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/","title":{"rendered":"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels"},"content":{"rendered":"<p>Het gloednieuwe Pixel Museum in Tour &amp; Taxis is volledig gewijd is aan videogames, en komt er onder meer dankzij de inspanningen van hub.brussels.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Het gloednieuwe Pixel Museum in Tour &amp; Taxis is volledig gewijd is aan videogames, en komt er onder meer dankzij de inspanningen van hub.brussels.<\/p>\n","protected":false},"author":2198,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false},"categories":[3],"tags":[],"class_list":["post-20990","post","type-post","status-publish","format-standard","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels - Diagnostic Export - hub.brussels<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels - Diagnostic Export - hub.brussels\" \/>\n<meta property=\"og:description\" content=\"Het gloednieuwe Pixel Museum in Tour &amp; Taxis is volledig gewijd is aan videogames, en komt er onder meer dankzij de inspanningen van hub.brussels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\" \/>\n<meta property=\"og:site_name\" content=\"Diagnostic Export - hub.brussels\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-16T13:04:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/testing.hub.brussels\/export\/wp-content\/uploads\/2025\/02\/simon-hattinga-verschure-5085-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mohammed Cherif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"mohammed Cherif\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\"},\"author\":{\"name\":\"mohammed Cherif\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/person\/fe15ef49c269c2f36447d91e13183b70\"},\"headline\":\"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels\",\"datePublished\":\"2020-10-16T13:04:19+00:00\",\"dateModified\":\"2020-10-16T13:04:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\"},\"wordCount\":38,\"publisher\":{\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#organization\"},\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\",\"url\":\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\",\"name\":\"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels - Diagnostic Export - hub.brussels\",\"isPartOf\":{\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#website\"},\"datePublished\":\"2020-10-16T13:04:19+00:00\",\"dateModified\":\"2020-10-16T13:04:19+00:00\",\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#website\",\"url\":\"https:\/\/testing.hub.brussels\/export\/nl\/\",\"name\":\"Diagnostic Export - hub.brussels\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#organization\"},\"alternateName\":\"Test de diagnostic \u00e0 l\u2019export\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/testing.hub.brussels\/export\/nl\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#organization\",\"name\":\"Diagnostic Export - hub.brussels\",\"url\":\"https:\/\/testing.hub.brussels\/export\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/testing.hub.brussels\/export\/wp-content\/uploads\/2022\/05\/hub_logo_cropped.svg\",\"contentUrl\":\"https:\/\/testing.hub.brussels\/export\/wp-content\/uploads\/2022\/05\/hub_logo_cropped.svg\",\"caption\":\"Diagnostic Export - hub.brussels\"},\"image\":{\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/person\/fe15ef49c269c2f36447d91e13183b70\",\"name\":\"mohammed Cherif\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4596633f4a806d71535ea3641bd47ea956601c1618dec2ba04a867b543d5af7e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4596633f4a806d71535ea3641bd47ea956601c1618dec2ba04a867b543d5af7e?s=96&d=mm&r=g\",\"caption\":\"mohammed Cherif\"},\"sameAs\":[\"https:\/\/rtfgbfgb\"],\"url\":\"https:\/\/testing.hub.brussels\/export\/nl\/author\/mohammed\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels - Diagnostic Export - hub.brussels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/","og_locale":"nl_NL","og_type":"article","og_title":"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels - Diagnostic Export - hub.brussels","og_description":"Het gloednieuwe Pixel Museum in Tour &amp; Taxis is volledig gewijd is aan videogames, en komt er onder meer dankzij de inspanningen van hub.brussels.","og_url":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/","og_site_name":"Diagnostic Export - hub.brussels","article_published_time":"2020-10-16T13:04:19+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/testing.hub.brussels\/export\/wp-content\/uploads\/2025\/02\/simon-hattinga-verschure-5085-1024x683.jpg","type":"image\/jpeg"}],"author":"mohammed Cherif","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"mohammed Cherif"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/#article","isPartOf":{"@id":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/"},"author":{"name":"mohammed Cherif","@id":"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/person\/fe15ef49c269c2f36447d91e13183b70"},"headline":"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels","datePublished":"2020-10-16T13:04:19+00:00","dateModified":"2020-10-16T13:04:19+00:00","mainEntityOfPage":{"@id":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/"},"wordCount":38,"publisher":{"@id":"https:\/\/testing.hub.brussels\/export\/nl\/#organization"},"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/","url":"https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/","name":"Naar een nieuwe level: het Pixel Museum en de Brusselse game-sector | hub.brussels - Diagnostic Export - hub.brussels","isPartOf":{"@id":"https:\/\/testing.hub.brussels\/export\/nl\/#website"},"datePublished":"2020-10-16T13:04:19+00:00","dateModified":"2020-10-16T13:04:19+00:00","inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/testing.hub.brussels\/export\/nl\/naar-een-nieuwe-level-het-pixel-museum-en-de-brusselse-game-sector-hub-brussels\/"]}]},{"@type":"WebSite","@id":"https:\/\/testing.hub.brussels\/export\/nl\/#website","url":"https:\/\/testing.hub.brussels\/export\/nl\/","name":"Diagnostic Export - hub.brussels","description":"","publisher":{"@id":"https:\/\/testing.hub.brussels\/export\/nl\/#organization"},"alternateName":"Test de diagnostic \u00e0 l\u2019export","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/testing.hub.brussels\/export\/nl\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/testing.hub.brussels\/export\/nl\/#organization","name":"Diagnostic Export - hub.brussels","url":"https:\/\/testing.hub.brussels\/export\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/testing.hub.brussels\/export\/wp-content\/uploads\/2022\/05\/hub_logo_cropped.svg","contentUrl":"https:\/\/testing.hub.brussels\/export\/wp-content\/uploads\/2022\/05\/hub_logo_cropped.svg","caption":"Diagnostic Export - hub.brussels"},"image":{"@id":"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/person\/fe15ef49c269c2f36447d91e13183b70","name":"mohammed Cherif","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/testing.hub.brussels\/export\/nl\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4596633f4a806d71535ea3641bd47ea956601c1618dec2ba04a867b543d5af7e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4596633f4a806d71535ea3641bd47ea956601c1618dec2ba04a867b543d5af7e?s=96&d=mm&r=g","caption":"mohammed Cherif"},"sameAs":["https:\/\/rtfgbfgb"],"url":"https:\/\/testing.hub.brussels\/export\/nl\/author\/mohammed\/"}]}},"_links":{"self":[{"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/posts\/20990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/users\/2198"}],"replies":[{"embeddable":true,"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/comments?post=20990"}],"version-history":[{"count":0,"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/posts\/20990\/revisions"}],"wp:attachment":[{"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/media?parent=20990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/categories?post=20990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/testing.hub.brussels\/export\/nl\/wp-json\/wp\/v2\/tags?post=20990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}